{"id":7290,"date":"2020-04-23T06:29:45","date_gmt":"2020-04-23T10:29:45","guid":{"rendered":"https:\/\/go.trader.ca\/?p=7290"},"modified":"2022-06-22T05:02:41","modified_gmt":"2022-06-22T09:02:41","slug":"la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance","status":"publish","type":"post","link":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/","title":{"rendered":"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance"},"content":{"rendered":"<p><em>R\u00e9dig\u00e9 par: Matt Lawson, vice-pr\u00e9sident, Logiciels commerciaux et Gestion avec les constructeurs \u2212 Soci\u00e9t\u00e9 TRADER<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Je commence cette lettre en exprimant ma plus profonde gratitude \u00e0 l\u2019endroit de tous les intervenants de premi\u00e8re ligne qui se d\u00e9vouent sans rel\u00e2che pour assurer la sant\u00e9 et le bien-\u00eatre de nos communaut\u00e9s, partout sur la plan\u00e8te. <\/p>\n<p>Les semaines et mois qui viennent comporteront leur lot d\u2019incertitudes, une situation pr\u00e9occupante pour tous. Nous avons d\u00e9j\u00e0 tous travers\u00e9 avec succ\u00e8s les eaux houleuses de r\u00e9cessions \u00e9conomiques, qui sont in\u00e9vitablement suivies de jours meilleurs. Les d\u00e9cisions que nous prendrons tout au long de cette p\u00e9riode influenceront la longueur et la difficult\u00e9 de nos retours respectifs \u00e0 la prosp\u00e9rit\u00e9. C\u2019est ainsi que certains commer\u00e7ants s\u2019en remettront plus rapidement que d\u2019autres. <\/p>\n<p>&nbsp;<\/p>\n<p><strong>Qu\u2019est-ce que \u00e7a signifie, concr\u00e8tement, pour tous mes amis et clients qui travaillent dans le secteur de la vente automobile? <\/strong><\/p>\n<p>Il est possible de diviser les co\u00fbts des commer\u00e7ants automobiles en trois grandes cat\u00e9gories: personnel, b\u00e2timents et inventaire. Les gouvernements, ainsi que les regroupements de concessionnaires et de marchands, ont r\u00e9agi \u00e0 un rythme jamais vu afin d\u2019all\u00e9ger le fardeau financier de tous les commer\u00e7ants automobiles et pour les aider \u00e0 g\u00e9rer leurs principaux centres de co\u00fbts. On a vu les constructeurs et les commer\u00e7ants prendre de tr\u00e8s grandes d\u00e9cisions en un temps record dans le but de pr\u00e9server leurs principales structures d\u2019affaires. J\u2019ai \u00e9t\u00e9 impressionn\u00e9 par toute cette ing\u00e9niosit\u00e9, ce qui me donne beaucoup d\u2019espoir.<\/p>\n<p>Ces sentiments sont apaisants, mais les commer\u00e7ants qui s\u2019en sortiront sont ceux qui rel\u00e8veront le plus grand d\u00e9fi de 2020: la gestion de leur inventaire. La grande majorit\u00e9 des conversations que j\u2019ai eues avec les commer\u00e7ants automobiles ces derni\u00e8res semaines se r\u00e9orientaient toutes vers un th\u00e8me commun: l\u2019incroyable incertitude des principaux param\u00e8tres sur lesquels ils se basent habituellement pour prendre leurs d\u00e9cisions.<\/p>\n<ul>\n<li>On ne sait plus quels sont les prix \u00e0 l\u2019encan;<\/li>\n<li>Comment g\u00e9rer selon le \u00ab\u00a0nombre de jours d\u2019approvisionnement du march\u00e9\u00a0\u00bb quand toutes les ventes sont pratiquement \u00e0 z\u00e9ro; <\/li>\n<li>Je m\u2019inqui\u00e8te de la taille de mon inventaire en fonction des conditions \u00e9conomiques actuelles, etc.<\/li>\n<\/ul>\n<p>En temps normal, le printemps g\u00e9n\u00e8re un volume \u00e9lev\u00e9 de v\u00e9hicules en fin de bail, de retours de v\u00e9hicules de flottes et les cours des encans et grossistes grouillent d\u2019activit\u00e9. Cette ann\u00e9e, c\u2019est tout le contraire. Ce que j\u2019entends de mes amis et clients, c\u2019est qu\u2019ils pr\u00e9voient que leurs taux de rotation passeront de 30 jours \u00e0 120 jours &#8211; ou plus&#8230; En une p\u00e9riode comme celle que l\u2019on traverse, il faut revenir \u00e0 la r\u00e8gle #1 des affaires: \u00ab\u00a0Cash is king\u00a0\u00bb. Alors, que faut-il faire pour pr\u00e9server ses liquidit\u00e9s?<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quelles actions devriez-vous consid\u00e9rer?<\/strong><\/p>\n<p>Prenons quelques secondes pour nous replacer dans le contexte. On sait que les mod\u00e8les 2021 commenceront \u00e0 arriver d\u2019ici les 2 \u00e0 4 prochains mois. Les cours des encans et grossistes automobiles d\u00e9borderont bient\u00f4t de retours de locations. Les constructeurs le savent tr\u00e8s bien et on voit qu\u2019ils ont d\u00e9j\u00e0 commenc\u00e9 \u00e0 adapter leurs offres en cons\u00e9quence. Ces trois facteurs joueront en la faveur des d\u00e9taillants automobiles qui auront acc\u00e8s aux liquidit\u00e9s suffisantes pour profiter la hausse de l\u2019offre aux encans et chez les grossistes. <\/p>\n<p>Est-ce que \u00e7a veut dire que vous devriez tout faire pour liquider votre inventaire? <em>Non, je ne crois pas.<\/em><\/p>\n<p>Devriez-vous passer en revue votre inventaire entier et ajuster les conditions de vente de chaque v\u00e9hicule? <em>Absolument.<\/em><\/p>\n<p>Vous devez r\u00e9examiner chacun de vos v\u00e9hicules, en fonction de la nouvelle r\u00e9alit\u00e9 du march\u00e9, et rien d\u2019autre. C\u2019est difficile \u00e0 croire, mais il a toujours un grand nombre d\u2019acheteurs potentiels dans le march\u00e9. Par exemple, notre place d\u2019affaires en ligne AutoHebdo.net g\u00e9n\u00e8re plus de 50 000 demandes directes de clients potentiels par semaine et notre trafic est rest\u00e9 pratiquement stable. Ce nombre de demandes par courriel (mesurables) signale clairement qu\u2019il y a toujours des acheteurs s\u00e9rieux, avec suffisamment d\u2019argent dans leurs poches. Il reste de nombreuses occasions de vente dans le march\u00e9, mais vous devez les attaquer d\u2019une mani\u00e8re chirurgicale. Ce n\u2019est plus le temps de \u00ab\u00a0r\u00e9ussir au volume\u00a0\u00bb (si je re\u00e7ois 100 demandes par mois, je conclus 8 ventes \u00e0 une moyenne de 2000$ par v\u00e9hicule). Vous devez r\u00e9\u00e9valuer chacun de vos v\u00e9hicules de mani\u00e8re approfondie, en fonction de votre march\u00e9 local et faire tous les efforts requis pour maximiser son potentiel. Je ne souhaite pas ici discr\u00e9diter le r\u00f4le du directeur de l\u2019usag\u00e9, en fait, c\u2019est tout le contraire, mais il important de souligner ceci: votre exp\u00e9rience du march\u00e9, bas\u00e9e sur une situation \u00ab\u00a0normale\u00a0\u00bb ne s\u2019applique plus en cette p\u00e9riode boulevers\u00e9e. Il y a une chose qui pourrait grandement vous aider: l\u2019acc\u00e8s \u00e0 des donn\u00e9es fra\u00eeches du march\u00e9 pour vous aider \u00e0 maximiser le profit de chaque v\u00e9hicule.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La cl\u00e9 du succ\u00e8s: la gestion d\u2019inventaire<\/strong><\/p>\n<p>Nos partenaires de vAuto n\u2019ont jamais pris autant au s\u00e9rieux leur mission: aider les commer\u00e7ants automobiles \u00e0 prendre des d\u00e9cisions qui sont plus complexes que jamais. Ainsi, ils con\u00e7oivent pr\u00e9sentement \u00e0 toute vitesse de nouveaux outils qui faciliteront la prise de telles d\u00e9cisions, en tenant compte de la grande incertitude des mesures habituelles comme le nombre de \u00ab\u00a0Jours d\u2019approvisionnement du march\u00e9\u00a0\u00bb, \u00ab\u00a0Co\u00fbt vs march\u00e9\u00a0\u00bb, et \u00ab\u00a0Prix vs march\u00e9\u00a0\u00bb. vAuto publiera tr\u00e8s bient\u00f4t la mise \u00e0 jour de ses syst\u00e8mes, qui inclura l\u2019envoi instantan\u00e9 de notifications pour vous tenir au courant des fluctuations du march\u00e9 (favorables ou d\u00e9favorables) dont vous devriez tenir compte.  Ces notifications comprendront des suggestions pour chacun de vos v\u00e9hicules (pas seulement par mod\u00e8le), selon les param\u00e8tres suivants: stabilit\u00e9 du march\u00e9, am\u00e9liorations, risques et tendances. Ces outils d\u2019aide \u00e0 la d\u00e9cision vous aideront \u00e0 mieux g\u00e9rer votre inventaire actuel et \u00e0 mieux orienter vos d\u00e9cisions d\u2019achat \u00e0 l\u2019encan ou chez les grossistes.<\/p>\n<p>L\u2019acc\u00e8s en temps r\u00e9el aux donn\u00e9es du march\u00e9 est plus important que jamais. L\u2019\u00e9quipe des gestionnaires de performance de vAuto travaille pr\u00e9sentement jour et nuit pour produire de nouveaux outils qui vous aideront \u00e0 mieux analyser et interpr\u00e9ter les riches donn\u00e9es utilis\u00e9es dans les syst\u00e8mes vAuto. Que vous soyez un commer\u00e7ant de coin de rue ou un prestigieux d\u00e9taillant r\u00e9gional, vous devrez tenir compte des suggestions de tous les outils de gestion d\u2019inventaire qui sont \u00e0 votre disposition pour prendre aujourd\u2019hui les d\u00e9cisions \u00e9clair\u00e9es qui assureront votre succ\u00e8s de demain.<\/p>\n<p>Alors que l\u2019on voit poindre \u00e0 l\u2019horizon les dates de r\u00e9ouverture des salles de montre partout au pays, c\u2019est plus que jamais le temps s\u2019atteler \u00e0 cette t\u00e2che. La Soci\u00e9t\u00e9 TRADER continue \u00e0 surveiller de tr\u00e8s pr\u00e8s le niveau d\u2019int\u00e9r\u00eat des consommateurs et, en collaboration avec nos partenaires de vAuto, nous serons l\u00e0 pour vous donner acc\u00e8s aux donn\u00e9es et outils qui nous aideront tous \u00e0 traverser ces eaux tumultueuses. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9dig\u00e9 par: Matt Lawson, vice-pr\u00e9sident, Logiciels commerciaux et Gestion avec les constructeurs \u2212 Soci\u00e9t\u00e9 TRADER &nbsp; Je commence cette lettre en exprimant ma plus profonde gratitude \u00e0 l\u2019endroit de tous les intervenants de premi\u00e8re ligne qui se d\u00e9vouent sans rel\u00e2che pour assurer la sant\u00e9 et le bien-\u00eatre de nos communaut\u00e9s, partout sur la plan\u00e8te. Les<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[749],"tags":[820,239,727,732,569,41],"class_list":["post-7290","post","type-post","status-publish","format-standard","hentry","category-articles","tag-autohebdo-net","tag-automobile","tag-consommateurs","tag-formation","tag-marketing-numerique","tag-place-daffaires"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance | Soci\u00e9t\u00e9 TRADER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance | Soci\u00e9t\u00e9 TRADER\" \/>\n<meta property=\"og:description\" content=\"R\u00e9dig\u00e9 par: Matt Lawson, vice-pr\u00e9sident, Logiciels commerciaux et Gestion avec les constructeurs \u2212 Soci\u00e9t\u00e9 TRADER &nbsp; Je commence cette lettre en exprimant ma plus profonde gratitude \u00e0 l\u2019endroit de tous les intervenants de premi\u00e8re ligne qui se d\u00e9vouent sans rel\u00e2che pour assurer la sant\u00e9 et le bien-\u00eatre de nos communaut\u00e9s, partout sur la plan\u00e8te. Les\" \/>\n<meta property=\"og:url\" content=\"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/\" \/>\n<meta property=\"og:site_name\" content=\"TRADER\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-23T10:29:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-22T09:02:41+00:00\" \/>\n<meta name=\"author\" content=\"Matt Lawson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matt Lawson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\\\/\"},\"author\":{\"name\":\"Matt Lawson\",\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#\\\/schema\\\/person\\\/b228beaa44ebf4e50cd96511e79389a0\"},\"headline\":\"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance\",\"datePublished\":\"2020-04-23T10:29:45+00:00\",\"dateModified\":\"2022-06-22T09:02:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\\\/\"},\"wordCount\":1261,\"publisher\":{\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#organization\"},\"keywords\":[\"AutoHebdo.net\",\"Automobile\",\"Consommateurs\",\"Formation\",\"Marketing num\u00e9rique\",\"Place d\u2019affaires\"],\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\\\/\",\"url\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\\\/\",\"name\":\"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance | Soci\u00e9t\u00e9 TRADER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#website\"},\"datePublished\":\"2020-04-23T10:29:45+00:00\",\"dateModified\":\"2022-06-22T09:02:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/go.trader.ca\\\/fr\\\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#website\",\"url\":\"https:\\\/\\\/go.trader.ca\\\/\",\"name\":\"AutoTrader.ca & AutoHebdo.net\",\"description\":\"La plus grande et r\u00e9put\u00e9e place d\u2019affaires automobile au Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/go.trader.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#organization\",\"name\":\"AutoTrader.ca & AutoHebdo.net\",\"url\":\"https:\\\/\\\/go.trader.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/go.trader.ca\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-AutoHebdo-FR.png\",\"contentUrl\":\"https:\\\/\\\/go.trader.ca\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo-AutoHebdo-FR.png\",\"width\":484,\"height\":52,\"caption\":\"AutoTrader.ca & AutoHebdo.net\"},\"image\":{\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/go.trader.ca\\\/#\\\/schema\\\/person\\\/b228beaa44ebf4e50cd96511e79389a0\",\"name\":\"Matt Lawson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f13aa6b1760fe4c7d9cf319520a43617f79c98b4b53f3d9f6abbf51b6ff8df42?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f13aa6b1760fe4c7d9cf319520a43617f79c98b4b53f3d9f6abbf51b6ff8df42?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f13aa6b1760fe4c7d9cf319520a43617f79c98b4b53f3d9f6abbf51b6ff8df42?s=96&d=mm&r=g\",\"caption\":\"Matt Lawson\"},\"sameAs\":[\"http:\\\/\\\/go.trader.ca\"],\"url\":\"https:\\\/\\\/go.trader.ca\\\/fr\\\/author\\\/matt-lawsontrader-ca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance | Soci\u00e9t\u00e9 TRADER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/","og_locale":"fr_FR","og_type":"article","og_title":"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance | Soci\u00e9t\u00e9 TRADER","og_description":"R\u00e9dig\u00e9 par: Matt Lawson, vice-pr\u00e9sident, Logiciels commerciaux et Gestion avec les constructeurs \u2212 Soci\u00e9t\u00e9 TRADER &nbsp; Je commence cette lettre en exprimant ma plus profonde gratitude \u00e0 l\u2019endroit de tous les intervenants de premi\u00e8re ligne qui se d\u00e9vouent sans rel\u00e2che pour assurer la sant\u00e9 et le bien-\u00eatre de nos communaut\u00e9s, partout sur la plan\u00e8te. Les","og_url":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/","og_site_name":"TRADER","article_published_time":"2020-04-23T10:29:45+00:00","article_modified_time":"2022-06-22T09:02:41+00:00","author":"Matt Lawson","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Matt Lawson","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/#article","isPartOf":{"@id":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/"},"author":{"name":"Matt Lawson","@id":"https:\/\/go.trader.ca\/#\/schema\/person\/b228beaa44ebf4e50cd96511e79389a0"},"headline":"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance","datePublished":"2020-04-23T10:29:45+00:00","dateModified":"2022-06-22T09:02:41+00:00","mainEntityOfPage":{"@id":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/"},"wordCount":1261,"publisher":{"@id":"https:\/\/go.trader.ca\/#organization"},"keywords":["AutoHebdo.net","Automobile","Consommateurs","Formation","Marketing num\u00e9rique","Place d\u2019affaires"],"articleSection":["Articles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/","url":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/","name":"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance | Soci\u00e9t\u00e9 TRADER","isPartOf":{"@id":"https:\/\/go.trader.ca\/#website"},"datePublished":"2020-04-23T10:29:45+00:00","dateModified":"2022-06-22T09:02:41+00:00","breadcrumb":{"@id":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/go.trader.ca\/fr\/la-gestion-serree-de-vos-stocks-la-cle-de-votre-relance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/go.trader.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"La gestion serr\u00e9e de vos stocks: la cl\u00e9 de votre relance"}]},{"@type":"WebSite","@id":"https:\/\/go.trader.ca\/#website","url":"https:\/\/go.trader.ca\/","name":"AutoTrader.ca & AutoHebdo.net","description":"La plus grande et r\u00e9put\u00e9e place d\u2019affaires automobile au Canada","publisher":{"@id":"https:\/\/go.trader.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/go.trader.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/go.trader.ca\/#organization","name":"AutoTrader.ca & AutoHebdo.net","url":"https:\/\/go.trader.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/go.trader.ca\/#\/schema\/logo\/image\/","url":"https:\/\/go.trader.ca\/wp-content\/uploads\/2024\/04\/Logo-AutoHebdo-FR.png","contentUrl":"https:\/\/go.trader.ca\/wp-content\/uploads\/2024\/04\/Logo-AutoHebdo-FR.png","width":484,"height":52,"caption":"AutoTrader.ca & AutoHebdo.net"},"image":{"@id":"https:\/\/go.trader.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/go.trader.ca\/#\/schema\/person\/b228beaa44ebf4e50cd96511e79389a0","name":"Matt Lawson","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f13aa6b1760fe4c7d9cf319520a43617f79c98b4b53f3d9f6abbf51b6ff8df42?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f13aa6b1760fe4c7d9cf319520a43617f79c98b4b53f3d9f6abbf51b6ff8df42?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f13aa6b1760fe4c7d9cf319520a43617f79c98b4b53f3d9f6abbf51b6ff8df42?s=96&d=mm&r=g","caption":"Matt Lawson"},"sameAs":["http:\/\/go.trader.ca"],"url":"https:\/\/go.trader.ca\/fr\/author\/matt-lawsontrader-ca\/"}]}},"_links":{"self":[{"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/posts\/7290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/comments?post=7290"}],"version-history":[{"count":0,"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/posts\/7290\/revisions"}],"wp:attachment":[{"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/media?parent=7290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/categories?post=7290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/go.trader.ca\/fr\/wp-json\/wp\/v2\/tags?post=7290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}